{"id":2464,"date":"2018-09-07T18:31:51","date_gmt":"2018-09-07T18:31:51","guid":{"rendered":"https:\/\/www.bellevuecollege.edu\/english\/?post_type=staff&#038;p=2464"},"modified":"2026-06-29T09:51:45","modified_gmt":"2026-06-29T16:51:45","slug":"travis-mckinney","status":"publish","type":"staff","link":"https:\/\/www.bellevuecollege.edu\/english\/staff\/travis-mckinney\/","title":{"rendered":"Travis Mckinney"},"content":{"rendered":"","protected":false},"author":11,"featured_media":2470,"parent":0,"comment_status":"closed","ping_status":"closed","template":"","class_list":["post-2464","staff","type-staff","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.bellevuecollege.edu\/english\/wp-json\/wp\/v2\/staff\/2464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bellevuecollege.edu\/english\/wp-json\/wp\/v2\/staff"}],"about":[{"href":"https:\/\/www.bellevuecollege.edu\/english\/wp-json\/wp\/v2\/types\/staff"}],"author":[{"embeddable":true,"href":"https:\/\/www.bellevuecollege.edu\/english\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bellevuecollege.edu\/english\/wp-json\/wp\/v2\/comments?post=2464"}],"version-history":[{"count":1,"href":"https:\/\/www.bellevuecollege.edu\/english\/wp-json\/wp\/v2\/staff\/2464\/revisions"}],"predecessor-version":[{"id":2467,"href":"https:\/\/www.bellevuecollege.edu\/english\/wp-json\/wp\/v2\/staff\/2464\/revisions\/2467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bellevuecollege.edu\/english\/wp-json\/wp\/v2\/media\/2470"}],"wp:attachment":[{"href":"https:\/\/www.bellevuecollege.edu\/english\/wp-json\/wp\/v2\/media?parent=2464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}