{"id":2534,"date":"2019-09-25T17:01:37","date_gmt":"2019-09-25T17:01:37","guid":{"rendered":"https:\/\/www.bellevuecollege.edu\/english\/?post_type=staff&#038;p=2534"},"modified":"2026-06-29T09:51:45","modified_gmt":"2026-06-29T16:51:45","slug":"mabel-josuva","status":"publish","type":"staff","link":"https:\/\/www.bellevuecollege.edu\/english\/staff\/mabel-josuva\/","title":{"rendered":"Mabel Josuva-Andrews"},"content":{"rendered":"","protected":false},"author":11,"featured_media":2937,"parent":0,"comment_status":"closed","ping_status":"closed","template":"","class_list":["post-2534","staff","type-staff","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.bellevuecollege.edu\/english\/wp-json\/wp\/v2\/staff\/2534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bellevuecollege.edu\/english\/wp-json\/wp\/v2\/staff"}],"about":[{"href":"https:\/\/www.bellevuecollege.edu\/english\/wp-json\/wp\/v2\/types\/staff"}],"author":[{"embeddable":true,"href":"https:\/\/www.bellevuecollege.edu\/english\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bellevuecollege.edu\/english\/wp-json\/wp\/v2\/comments?post=2534"}],"version-history":[{"count":2,"href":"https:\/\/www.bellevuecollege.edu\/english\/wp-json\/wp\/v2\/staff\/2534\/revisions"}],"predecessor-version":[{"id":2814,"href":"https:\/\/www.bellevuecollege.edu\/english\/wp-json\/wp\/v2\/staff\/2534\/revisions\/2814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bellevuecollege.edu\/english\/wp-json\/wp\/v2\/media\/2937"}],"wp:attachment":[{"href":"https:\/\/www.bellevuecollege.edu\/english\/wp-json\/wp\/v2\/media?parent=2534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}